{"id":5497,"date":"2021-11-18T08:30:10","date_gmt":"2021-11-18T07:30:10","guid":{"rendered":"https:\/\/poptranslation.com\/2020\/09\/08\/traductions-urgentes-lurgence-ne-doit-rien-enlever-a-la-qualite\/"},"modified":"2022-07-07T11:53:47","modified_gmt":"2022-07-07T09:53:47","slug":"traductions-urgentes","status":"publish","type":"post","link":"https:\/\/poptranslation.com\/fr\/traductions-urgentes\/","title":{"rendered":"Traductions urgentes : l\u2019urgence <br> ne doit rien enlever \u00e0 la qualit\u00e9 !"},"content":{"rendered":"[vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb]<div class=\"sharing-default-minimal\"><div class=\"nectar-social default\" data-position=\"left\" data-color-override=\"override\"><div class=\"nectar-social-inner\"><a class='facebook-share nectar-sharing' href='#' title='Share this'>  <i class='fa fa-facebook'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='twitter-share nectar-sharing' href='#' title='Share this'> <i class='fa icon-salient-x-twitter'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='linkedin-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-linkedin'><\/i> <span class='social-text'>Share<\/span> <\/a><\/div><\/div><\/div>[vc_column_text]\n<h4>Effectuer des traductions urgentes ne signifie pas renoncer \u00e0 la qualit\u00e9 des textes traduits. De nos jours, les besoins de communication rapides obligent les agences de traduction \u00e0 offrir des services ex\u00e9cut\u00e9es dans les plus brefs d\u00e9lais. Cependant, il est \u00e9galement important qu&rsquo;ils veillent \u00e0 la qualit\u00e9 des textes qu&rsquo;ils livrent.<\/h4>\n[\/vc_column_text][image_with_animation image_url=\u00a0\u00bb35915&Prime; animation=\u00a0\u00bbFade In\u00a0\u00bb hover_animation=\u00a0\u00bbnone\u00a0\u00bb alignment=\u00a0\u00bb\u00a0\u00bb border_radius=\u00a0\u00bbnone\u00a0\u00bb box_shadow=\u00a0\u00bbnone\u00a0\u00bb image_loading=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb max_width_mobile=\u00a0\u00bbdefault\u00a0\u00bb][vc_column_text]\n<ul>\n<li>\n<h4>Qu&rsquo;est-ce qu&rsquo;une traduction urgente ?<\/h4>\n<\/li>\n<\/ul>\n<p>Le terme \u00ab\u00a0urgent\u00a0\u00bb peut \u00eatre interpr\u00e9t\u00e9 de diff\u00e9rentes mani\u00e8res, en fonction de la vision et de la situation personnelle de chacun. Certains entendent par \u00ab\u00a0urgent\u00a0\u00bb une traduction qui doit \u00eatre faite en une heure et d&rsquo;autres qui doit \u00eatre faite d&rsquo;un jour \u00e0 l&rsquo;autre. Le nombre de mots et le d\u00e9lai d\u00e9terminent, entre autres, l&rsquo;urgence d&rsquo;une traduction. Le chef de projet de l&rsquo;entreprise de traduction d\u00e9terminera l&rsquo;urgence d&rsquo;une commande de traduction en fonction de ces variables et d&rsquo;autres encore. C&rsquo;est l&rsquo;une des caract\u00e9ristiques de ce type de traduction qui doit \u00eatre prise en compte tant au moment o\u00f9 elle est propos\u00e9e que lorsqu&rsquo;elle est contract\u00e9e.<\/p>\n<p>Il est important de savoir que ceux qui fournissent ce service de <strong>traductions urgentes<\/strong> doivent savoir que, dans de nombreux cas, ils devront travailler en dehors des heures de travail, faire des heures suppl\u00e9mentaires, le faire le week-end ou laisser d&rsquo;autres travaux en suspens afin de donner la priorit\u00e9 aux urgences.<br \/>\nEn outre, ils doivent tenir compte du fait qu&rsquo;au-del\u00e0 de la n\u00e9cessit\u00e9 de livrer un travail de traduction en urgence, il doit offrir une qualit\u00e9 conforme \u00e0 ce que le client. Il incombera donc \u00e0 l&rsquo;entreprise et aux traducteurs qui composent l&rsquo;\u00e9quipe, de livrer des textes traduits d&rsquo;excellente qualit\u00e9. En ce sens, effectuer des traductions urgentes signifie offrir une qualit\u00e9 de service optimale dans les plus brefs d\u00e9lais.<\/p>\n<ul>\n<li>\n<h4>Caract\u00e9ristiques des traductions urgentes<\/h4>\n<\/li>\n<\/ul>\n<p>Lorsque nous parlons de traductions urgentes, nous sommes toujours assaillis par les m\u00eames doutes. Par exemple : une traduction urgente a-t-elle le m\u00eame tarif qu&rsquo;une traduction en temps normal ? Le professionnel de la traduction, comme celui de tout autre domaine, a des horaires de travail normaux, des engagements assum\u00e9s, des travaux en attente&#8230;<br \/>\nPar cons\u00e9quent, si vous devez reporter la livraison d&rsquo;autres travaux ou faire des heures suppl\u00e9mentaires en dehors de vos heures habituelles, il est \u00e9vident que le taux pour un emploi urgent ne peut pas \u00eatre \u00e9gal \u00e0 la valeur de votre taux de travail habituel. Dans ce cas, les traductions urgentes sont g\u00e9n\u00e9ralement factur\u00e9es \u00e0 un tarif plus \u00e9lev\u00e9 que les traductions non urgentes.<\/p>\n<p>Une autre question qu&rsquo;un client pose lorsqu&rsquo;il commande une traduction urgente est de savoir de quoi d\u00e9pend la qualit\u00e9 du texte final. Comme indiqu\u00e9 ci-dessus, la rapidit\u00e9 de la traduction ne doit pas affecter la qualit\u00e9. Cependant, d&rsquo;autres facteurs peuvent interf\u00e9rer avec la production.<br \/>\nEn principe, le choix de l&rsquo;entreprise et des professionnels qui seront charg\u00e9s de la traduction est un facteur cl\u00e9 pour garantir la qualit\u00e9 des traductions urgentes. Dans ce cas, lorsqu&rsquo;il s&rsquo;agit de ce type de travail, il est conseill\u00e9 de choisir une agence ou un professionnel de la traduction ayant fait ses preuves. Tous les traducteurs ne font pas de traductions urgentes (ou tous ne les font pas avec qualit\u00e9).<\/p>\n<p>Un autre \u00e9l\u00e9ment \u00e0 prendre en compte est la complexit\u00e9 du travail. Par exemple, la traduction d&rsquo;un site web n&rsquo;a pas le m\u00eame degr\u00e9 de complexit\u00e9 que la traduction d&rsquo;un essai clinique ou d&rsquo;un manuel technique pour un aspirateur. Le degr\u00e9 de sp\u00e9cialisation du texte \u00e0 traduire est sans aucun doute un autre facteur cl\u00e9 lorsqu&rsquo;il s&rsquo;agit de faire une traduction urgente et d&rsquo;estimer son tarif et son d\u00e9lai de livraison.<br \/>\nComme nous l&rsquo;avons d\u00e9j\u00e0 dit, il est \u00e9vident que la longueur affecte \u00e9galement la capacit\u00e9 \u00e0 traduire un document dans un court laps de temps.<\/p>\n<p>Enfin, il est important que le client informe l&rsquo;agence ou le traducteur professionnel de l&rsquo;urgence r\u00e9elle de la mission ; c&rsquo;est-\u00e0-dire qu&rsquo;il sera toujours pr\u00e9f\u00e9rable de fixer le d\u00e9lai r\u00e9el pour les traductions urgentes, et donc de donner la possibilit\u00e9 au professionnel de le faire en toute tranquillit\u00e9.<br \/>\nG\u00e9n\u00e9ralement, les agences de traduction \u00e9tablissent des devis personnalis\u00e9s et informent ainsi, en plus du devis, de la date exacte de livraison.<\/p>\n<ul>\n<li>\n<h4>Exemples de traductions urgentes<\/h4>\n<\/li>\n<\/ul>\n<p>Effectuer des traductions urgentes tout en offrant une excellente qualit\u00e9 est l&rsquo;un des d\u00e9fis auxquels sont confront\u00e9s ceux qui travaillent sur le march\u00e9 de la traduction.<\/p>\n<p>Une traduction peut \u00eatre demand\u00e9e en peu de temps, par exemple, lorsque le client doit se rendre \u00e0 l&rsquo;\u00e9tranger pour travailler ou \u00e9tudier. En r\u00e8gle g\u00e9n\u00e9rale, cela n\u00e9cessite des traductions asserment\u00e9es qui peuvent \u00eatre effectu\u00e9es en un temps record ; c&rsquo;est un aspect de la traduction urgente les plus demand\u00e9es.<\/p>\n<p>Un autre exemple est qu&rsquo;actuellement les entreprises centralisent la plupart de leurs communications par le biais d&rsquo;Internet. Les blogs, les bulletins d&rsquo;information, les commentaires, les suggestions et les pages de fans sont les formes de communication les plus utilis\u00e9es par les institutions et les entreprises pour atteindre leurs clients potentiels. Le web est \u00e9galement transform\u00e9 en une grande vitrine sur le monde ext\u00e9rieur ; des personnes de diff\u00e9rentes nationalit\u00e9s peuvent visiter le site web d&rsquo;une entreprise et devenir ainsi ses clients potentiels.<br \/>\nC&rsquo;est pourquoi les entreprises voient la n\u00e9cessit\u00e9 de <a href=\"https:\/\/poptranslation.com\/blog\/traduction-ou-localisation-un-choix-strategique\"><strong>traduire un site web<\/strong><\/a>, un blog, une newsletter ou des <a href=\"https:\/\/poptranslation.com\/blog\/pourquoi-traduire-le-contenu-des-reseaux-sociaux\"><strong>messages sur les r\u00e9seaux sociaux<\/strong><\/a>. Dans ce cas, les traductions urgentes sont \u00e9galement tr\u00e8s utiles dans le cadre de l&rsquo;am\u00e9lioration des processus de traduction pour les entreprises.<\/p>\n<p>Un autre exemple (et d\u2019actualit\u00e9) de traduction urgente est celui requis par les h\u00f4pitaux ou les centres m\u00e9dicaux lorsqu&rsquo;ils traitent des patients \u00e9trangers. Cette situation est tr\u00e8s courante dans les grandes villes ou dans les centres touristiques o\u00f9 se rendent des personnes de diff\u00e9rentes nationalit\u00e9s. Dans certains cas, l&rsquo;institution peut faire appel \u00e0 des interpr\u00e8tes pour les aider \u00e0 comprendre ce qui arrive au patient ; cependant, s&rsquo;il est n\u00e9cessaire de pr\u00e9senter un rapport ou une explication d&rsquo;un traitement de longue dur\u00e9e \u00e0 des professionnels de la sant\u00e9 dans leur pays d&rsquo;origine, des traductions m\u00e9dicales urgentes peuvent \u00eatre demand\u00e9es.<\/p>\n<p><strong>Vous avez besoin d&rsquo;une traduction urgente ? N\u2019h\u00e9sitez pas \u00e0 <a href=\"https:\/\/poptranslation.com\/devis\">contacter Pop translation<\/a>.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb top_margin=\u00a0\u00bb25&Prime; centered_text=\u00a0\u00bbtrue\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][nectar_btn size=\u00a0\u00bbjumbo\u00a0\u00bb button_style=\u00a0\u00bbregular\u00a0\u00bb button_color_2=\u00a0\u00bbAccent-Color\u00a0\u00bb icon_family=\u00a0\u00bbnone\u00a0\u00bb button_id=\u00a0\u00bbcallButtonHome\u00a0\u00bb url=\u00a0\u00bbtel:+33680351098&Prime;][\/vc_column][\/vc_row][vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_raw_js]JTNDc2NyaXB0JTNFJTBBJTA5ZG9jdW1lbnQuZ2V0RWxlbWVudEJ5SWQlMjglMjJjYWxsQnV0dG9uSG9tZSUyMiUyOS5pbm5lckhUTUwlMjAlM0QlMjAlMjIlM0NkaXYlMjBzdHlsZSUzRCUyN2ZvbnQtc2l6ZSUzQTE5cHglM0IlMjclM0UlM0NpbWclMjBzdHlsZSUzRCUyN2Zsb2F0JTNBbGVmdCUzQm1hcmdpbi1yaWdodCUzQTVweCUzQm1hcmdpbi10b3AlM0EtNXB4JTI3JTIwc3JjJTNEJTI3aHR0cHMlM0ElMkYlMkZwb3B0cmFuc2xhdGlvbi5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjElMkYwNyUyRlB0LXNpdGUtc3ltYm9sZS10ZWxlcGhvbmUucG5nJTI3JTIwYWx0JTNEJTI3JTI3JTIwd2lkdGglM0QlMjcxOCUyNyUyMGhlaWdodCUzRCUyNzE4JTI3JTIwJTJGJTNFJTJCMzMlMjA2JTIwODAlMjAzNSUyMDEwJTIwOTglM0MlMkZkaXYlM0UlMjIlM0IlMEElM0MlMkZzY3JpcHQlM0U=[\/vc_raw_js][\/vc_column][\/vc_row][vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb phone_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb column_border_width=\u00a0\u00bbnone\u00a0\u00bb column_border_style=\u00a0\u00bbsolid\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column_text]\n<h4>Lire aussi :<a href=\"https:\/\/poptranslation.com\/quest-ce-quune-agence-de-traduction-et-comment-fonctionne-t-elle\/\"> Comment fonctionne une agence de traduction ?<\/a><\/h4>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00a0\u00bbin_container\u00a0\u00bb full_screen_row_position=\u00a0\u00bbmiddle\u00a0\u00bb column_margin=\u00a0\u00bbdefault\u00a0\u00bb column_direction=\u00a0\u00bbdefault\u00a0\u00bb column_direction_tablet=\u00a0\u00bbdefault\u00a0\u00bb column_direction_phone=\u00a0\u00bbdefault\u00a0\u00bb scene_position=\u00a0\u00bbcenter\u00a0\u00bb text_color=\u00a0\u00bbdark\u00a0\u00bb text_align=\u00a0\u00bbleft\u00a0\u00bb row_border_radius=\u00a0\u00bbnone\u00a0\u00bb row_border_radius_applies=\u00a0\u00bbbg\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb shape_divider_position=\u00a0\u00bbbottom\u00a0\u00bb bg_image_animation=\u00a0\u00bbnone\u00a0\u00bb][vc_column column_padding=\u00a0\u00bbno-extra-padding\u00a0\u00bb column_padding_tablet=\u00a0\u00bbinherit\u00a0\u00bb column_padding_phone=\u00a0\u00bbinherit\u00a0\u00bb column_padding_position=\u00a0\u00bball\u00a0\u00bb background_color_opacity=\u00a0\u00bb1&Prime; background_hover_color_opacity=\u00a0\u00bb1&Prime; column_shadow=\u00a0\u00bbnone\u00a0\u00bb column_border_radius=\u00a0\u00bbnone\u00a0\u00bb column_link_target=\u00a0\u00bb_self\u00a0\u00bb gradient_direction=\u00a0\u00bbleft_to_right\u00a0\u00bb overlay_strength=\u00a0\u00bb0.3&Prime; width=\u00a0\u00bb1\/1&Prime; tablet_width_inherit=\u00a0\u00bbdefault\u00a0\u00bb tablet_text_alignment=\u00a0\u00bbdefault\u00a0\u00bb&#8230;<\/p>\n","protected":false},"author":2490,"featured_media":35915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[207,211,217,237,252,257],"tags":[],"class_list":["post-5497","post","type-post","status-publish","format-standard","has-post-thumbnail","category-multilingue","category-prestation-de-services","category-qualite","category-traduction","category-urgence","category-vitesse"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/posts\/5497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/users\/2490"}],"replies":[{"embeddable":true,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/comments?post=5497"}],"version-history":[{"count":17,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/posts\/5497\/revisions"}],"predecessor-version":[{"id":36078,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/posts\/5497\/revisions\/36078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/media\/35915"}],"wp:attachment":[{"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/media?parent=5497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/categories?post=5497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poptranslation.com\/fr\/wp-json\/wp\/v2\/tags?post=5497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}